{"id":4758,"date":"2025-04-23T20:08:33","date_gmt":"2025-04-23T20:08:33","guid":{"rendered":"https:\/\/www.arecibo.pr\/?page_id=4758"},"modified":"2025-08-25T16:03:26","modified_gmt":"2025-08-25T16:03:26","slug":"bancos-y-cooperativas-de-arecibo","status":"publish","type":"page","link":"https:\/\/www.arecibo.pr\/en\/bancos-y-cooperativas-de-arecibo\/","title":{"rendered":"Bancos y Cooperativas de Arecibo"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-enbxd5ql alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-mfy7shn2 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Bancas y Cooperativas de Arecibo<\/h2><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-uagb-slider uagb-block-4e27f818 uagb-slider-container\"><div class=\"uagb-slides uagb-swiper\"><div class=\"swiper-wrapper\">\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-539e6df7\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-cfa3fb96 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-957cf1e0 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"> \u00abConfianza financiera con rostro local\u00bb<\/h3><\/div><p class=\"uagb-ifb-desc\">Explora las cooperativas y bancos que forman parte del motor econ\u00f3mico de Arecibo. Desde pr\u00e9stamos accesibles hasta soluciones digitales modernas, estas instituciones est\u00e1n comprometidas con el bienestar de nuestra comunidad.<\/p><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-c7f84351\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-f53ec393 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-83bf24d1 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Soluciones financieras para cada etapa de tu vida<\/h3><\/div><p class=\"uagb-ifb-desc\">Ya sea que busques financiar tu hogar, emprender un negocio o manejar tus ahorros, aqu\u00ed encontrar\u00e1s opciones personalizadas que se ajustan a tus necesidades. Descubre lo que ofrecen nuestras instituciones aliadas.<\/p><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-26ef4f97 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><div class=\"root-eb-post-grid-c6937 wp-block-essential-blocks-post-grid\">\n    <div class=\"eb-parent-wrapper eb-parent-eb-post-grid-c6937 \">\n        <div class=\"eb-post-grid-c6937 style-1  eb-post-grid-wrapper\"\n            data-id=\"eb-post-grid-c6937\"\n            data-querydata=\"{&quot;source&quot;:&quot;post&quot;,&quot;sourceIndex&quot;:0,&quot;rest_base&quot;:&quot;posts&quot;,&quot;rest_namespace&quot;:&quot;wp\\\/v2&quot;,&quot;author&quot;:&quot;&quot;,&quot;taxonomies&quot;:{&quot;category&quot;:{&quot;name&quot;:&quot;Categor\\u00edas&quot;,&quot;rest_base&quot;:&quot;categories&quot;,&quot;rest_namespace&quot;:&quot;wp\\\/v2&quot;,&quot;slug&quot;:&quot;category&quot;,&quot;value&quot;:&quot;[{\\&quot;value\\&quot;:120,\\&quot;label\\&quot;:\\&quot;Banca y Cooperativas\\&quot;}]&quot;}},&quot;per_page&quot;:&quot;6&quot;,&quot;offset&quot;:&quot;0&quot;,&quot;orderby&quot;:&quot;modified&quot;,&quot;order&quot;:&quot;desc&quot;,&quot;include&quot;:&quot;&quot;,&quot;exclude&quot;:&quot;&quot;,&quot;exclude_current&quot;:false,&quot;ignore_sticky_posts&quot;:false,&quot;exclude_password_protected&quot;:false}\"\n            data-attributes=\"{&quot;thumbnailSize&quot;:&quot;&quot;,&quot;loadMoreOptions&quot;:{&quot;enableMorePosts&quot;:true,&quot;loadMoreType&quot;:&quot;2&quot;,&quot;loadMoreButtonTxt&quot;:&quot;Load More&quot;,&quot;alignment&quot;:&quot;center&quot;,&quot;prevTxt&quot;:&quot;&lt;&quot;,&quot;nextTxt&quot;:&quot;&gt;&quot;,&quot;totalPosts&quot;:2},&quot;showSearch&quot;:false,&quot;showTaxonomyFilter&quot;:false,&quot;enableAjaxSearch&quot;:false,&quot;addIcon&quot;:false,&quot;iconPosition&quot;:&quot;left&quot;,&quot;icon&quot;:&quot;fas fa-chevron-right&quot;,&quot;preset&quot;:&quot;style-1&quot;,&quot;defaultFilter&quot;:&quot;all&quot;,&quot;version&quot;:&quot;v2&quot;,&quot;showBlockContent&quot;:true,&quot;showFallbackImg&quot;:false,&quot;fallbackImgUrl&quot;:&quot;&quot;,&quot;showThumbnail&quot;:true,&quot;showTitle&quot;:true,&quot;titleLength&quot;:30,&quot;titleTag&quot;:&quot;h2&quot;,&quot;showContent&quot;:true,&quot;contentLength&quot;:12,&quot;expansionIndicator&quot;:&quot;...&quot;,&quot;showReadMore&quot;:false,&quot;readmoreText&quot;:&quot;Read More&quot;,&quot;showMeta&quot;:true,&quot;headerMeta&quot;:&quot;[]&quot;,&quot;footerMeta&quot;:&quot;[]&quot;,&quot;authorPrefix&quot;:&quot;by&quot;,&quot;datePrefix&quot;:&quot;on&quot;,&quot;showFeaturedPost&quot;:false,&quot;featuredPostId&quot;:&quot;&quot;,&quot;showFeaturedPostTitle&quot;:true,&quot;showFeaturedPostContent&quot;:false,&quot;showFeaturedPostMeta&quot;:true,&quot;showFeaturedHeaderMeta&quot;:true,&quot;showFeaturedFooterMeta&quot;:true,&quot;featuredMetaItems&quot;:&quot;{}&quot;,&quot;featuredExcerptLength&quot;:10}\">\n\n            \n\n            <div class=\"eb-post-grid-posts-wrapper\"><article class=\"ebpg-grid-post ebpg-post-grid-column\" data-id=\"5364\"><div class=\"ebpg-grid-post-holder\"><div class=\"ebpg-entry-wrapper\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/www.arecibo.pr\/en\/cooperativa-coopaca\/\">Cooperativa CooPACA<\/a>\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/08\/454407649_942362681251084_8768533740160212015_n.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><header class=\"ebpg-entry-header\">\n            <h2 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-grid-post-link\" href=\"https:\/\/www.arecibo.pr\/en\/cooperativa-coopaca\/\" title=\"cooperativacoopaca\">Cooperativa CooPACA<\/a>\n            <\/h2>\n        <\/header><div class=\"ebpg-entry-meta ebpg-header-meta\"><div class=\"ebpg-entry-meta-items\"><\/div><\/div><div class=\"ebpg-entry-content\"><div class=\"ebpg-grid-post-excerpt\">\n            <p>Cooperativa CooPACA\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nEn el coraz\u00f3n de Arecibo, hace casi 80 a\u00f1os, naci\u00f3&#8230;<\/p>\n        <\/div><\/div><div class=\"ebpg-entry-meta ebpg-footer-meta\"><div class=\"ebpg-entry-meta-items\"><\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-grid-post ebpg-post-grid-column\" data-id=\"4765\"><div class=\"ebpg-grid-post-holder\"><div class=\"ebpg-entry-wrapper\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/www.arecibo.pr\/en\/cooperativa-zeno-gandia-70-anos-de-compromiso-con-arecibo\/\">Cooperativa Zeno Gand\u00eda<\/a>\n                    <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/481174195_1059146806241265_4163197774418453975_n.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><header class=\"ebpg-entry-header\">\n            <h2 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-grid-post-link\" href=\"https:\/\/www.arecibo.pr\/en\/cooperativa-zeno-gandia-70-anos-de-compromiso-con-arecibo\/\" title=\"cooperativazenoganda\">Cooperativa Zeno Gand\u00eda<\/a>\n            <\/h2>\n        <\/header><div class=\"ebpg-entry-meta ebpg-header-meta\"><div class=\"ebpg-entry-meta-items\"><\/div><\/div><div class=\"ebpg-entry-content\"><div class=\"ebpg-grid-post-excerpt\">\n            <p>Cooperativa Zeno Gand\u00eda: 70 a\u00f1os de compromiso con Arecibo\n\n\n\n\n\n\n\n\n\n\n\n\nDesde hace m\u00e1s&#8230;<\/p>\n        <\/div><\/div><div class=\"ebpg-entry-meta ebpg-footer-meta\"><div class=\"ebpg-entry-meta-items\"><\/div><\/div><\/div><\/div><\/article><\/div><p class=\"eb-no-posts eb-loadmore-no-post\" style=\"display: none;\">No more posts<\/p>        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","pmpro_default_level":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"iawp_total_views":74,"footnotes":""},"class_list":["post-4758","page","type-page","status-publish","hentry","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bancos y Cooperativas de Arecibo - Arecibo.pr<\/title>\n<meta name=\"description\" content=\"Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arecibo.pr\/en\/bancos-y-cooperativas-de-arecibo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bancos y Cooperativas de Arecibo\" \/>\n<meta property=\"og:description\" content=\"Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arecibo.pr\/en\/bancos-y-cooperativas-de-arecibo\/\" \/>\n<meta property=\"og:site_name\" content=\"Arecibo.pr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61575723174236\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T16:03:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/bancos-y-cooperativas-de-arecibo\\\/\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/bancos-y-cooperativas-de-arecibo\\\/\",\"name\":\"Bancos y Cooperativas de Arecibo - Arecibo.pr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#website\"},\"datePublished\":\"2025-04-23T20:08:33+00:00\",\"dateModified\":\"2025-08-25T16:03:26+00:00\",\"description\":\"Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/bancos-y-cooperativas-de-arecibo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arecibo.pr\\\/bancos-y-cooperativas-de-arecibo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/bancos-y-cooperativas-de-arecibo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.arecibo.pr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bancos y Cooperativas de Arecibo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#website\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/\",\"name\":\"Arecibo.pr\",\"description\":\"La Villa del Capit&aacute;n Correa LIVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arecibo.pr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#organization\",\"name\":\"Arecibo.pr\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png\",\"width\":378,\"height\":92,\"caption\":\"Arecibo.pr\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61575723174236\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bancos y Cooperativas de Arecibo - Arecibo.pr","description":"Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arecibo.pr\/en\/bancos-y-cooperativas-de-arecibo\/","og_locale":"en_US","og_type":"article","og_title":"Bancos y Cooperativas de Arecibo","og_description":"Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar.","og_url":"https:\/\/www.arecibo.pr\/en\/bancos-y-cooperativas-de-arecibo\/","og_site_name":"Arecibo.pr","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61575723174236","article_modified_time":"2025-08-25T16:03:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arecibo.pr\/bancos-y-cooperativas-de-arecibo\/","url":"https:\/\/www.arecibo.pr\/bancos-y-cooperativas-de-arecibo\/","name":"Bancos y Cooperativas de Arecibo - Arecibo.pr","isPartOf":{"@id":"https:\/\/www.arecibo.pr\/#website"},"datePublished":"2025-04-23T20:08:33+00:00","dateModified":"2025-08-25T16:03:26+00:00","description":"Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar.","breadcrumb":{"@id":"https:\/\/www.arecibo.pr\/bancos-y-cooperativas-de-arecibo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arecibo.pr\/bancos-y-cooperativas-de-arecibo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.arecibo.pr\/bancos-y-cooperativas-de-arecibo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.arecibo.pr\/"},{"@type":"ListItem","position":2,"name":"Bancos y Cooperativas de Arecibo"}]},{"@type":"WebSite","@id":"https:\/\/www.arecibo.pr\/#website","url":"https:\/\/www.arecibo.pr\/","name":"Arecibo.pr","description":"La Villa del Capit&aacute;n Correa LIVE","publisher":{"@id":"https:\/\/www.arecibo.pr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arecibo.pr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arecibo.pr\/#organization","name":"Arecibo.pr","url":"https:\/\/www.arecibo.pr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arecibo.pr\/#\/schema\/logo\/image\/","url":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/02\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png","contentUrl":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/02\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png","width":378,"height":92,"caption":"Arecibo.pr"},"image":{"@id":"https:\/\/www.arecibo.pr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61575723174236"]}]}},"spectra_custom_meta":{"_rtcl_block_active":["1"],"_rtcl_block_css":[""],"_rtcl_gb_attr":[""],"_eb_attr":[""],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":["disabled"],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"_themeisle_gutenberg_block_has_review":[""],"iawp_total_views":["74"],"footnotes":[""],"wppb-ul-default-all-users-template":[""],"wppb-ul-default-single-user-template":[""],"wppb-ul-active-theme":["default"],"_wpuf_form_id":[""],"_wpuf_lock_editing_post":["no"],"_wpuf_res_display":["all"],"_seopress_redirections_type":["301"],"_seopress_redirections_logged_status":["both"],"_seopress_analysis_target_kw":[""],"_eb_reusable_block_ids":["a:0:{}"],"_dp_original":["3361"],"_edit_lock":["1756138252:1"],"_edit_last":["1"],"pmpro_default_level":[""],"_yoast_indexnow_last_ping":["1756137697"],"_yoast_wpseo_focuskw":["Bancos en Arecibo Cooperativas en Arecibo"],"_yoast_wpseo_metadesc":["Descubre los principales bancos y cooperativas en Arecibo, Puerto Rico. Encuentra informaci\u00f3n sobre cuentas, pr\u00e9stamos, financiamiento, cajeros autom\u00e1ticos y servicios financieros en un solo lugar."],"_yoast_wpseo_linkdex":["54"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_focuskeywords":[""],"_yoast_wpseo_keywordsynonyms":[""],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_uag_css_file_name":["uag-css-4758.css"],"_uag_js_file_name":["uag-js-4758.js"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:4;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:3;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:1;s:17:\"uagb\/slider-child\";i:2;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1770939859"],"_uag_page_assets":["a:9:{s:3:\"css\";s:134417:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.uagb-swiper{position:relative;overflow:hidden}.uagb-slider-container{position:relative;width:100%;min-width:0;transition:box-shadow .2s ease}.uagb-slider-container .swiper-notification{left:0;opacity:0;pointer-events:none;position:absolute;top:0;z-index:-1000}.uagb-slider-container .swiper-button-next.swiper-button-disabled,.uagb-slider-container .swiper-button-prev.swiper-button-disabled{pointer-events:all}.uagb-slider-container .swiper-pagination.swiper-pagination-bullets{max-width:100%}.uagb-slider-container .swiper-button-prev,.uagb-slider-container .swiper-button-next{border-style:none;background:#efefef}.uagb-slider-container.slider-focus-mode .swiper-slide::before{content:\"\";position:absolute;left:0;right:0;top:0;bottom:0;height:100%;width:100%;z-index:99;transition-property:background}.uagb-slider-container.slider-focus-mode .swiper-slide.swiper-slide-active::before{pointer-events:none}\n.wp-block-uagb-container.uagb-block-enbxd5ql .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-enbxd5ql .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-enbxd5ql .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-enbxd5ql .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-enbxd5ql .uagb-container__video-wrap video{opacity: 0.5;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-enbxd5ql{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-enbxd5ql > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1285px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-enbxd5ql{min-height: 27px;box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 42% 52%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/9076.jpg);background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-enbxd5ql::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-8);opacity: 0.5;}.uagb-block-mfy7shn2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-mfy7shn2 .uagb-ifb-icon svg{fill: #333;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-mfy7shn2 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-mfy7shn2 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-mfy7shn2 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-mfy7shn2 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-mfy7shn2 .uagb-ifb-title{font-size: 53px;color: #ffffff;margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-mfy7shn2 .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-mfy7shn2 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-mfy7shn2 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-mfy7shn2 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-mfy7shn2 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-mfy7shn2 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-mfy7shn2.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-mfy7shn2 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-slider-container.uagb-block-4e27f818{box-shadow: 0px 0px 0 #00000070;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container{border-color: #4B4F58;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-pagination-bullet{background-color: #333333;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container .swiper-button-prev{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;color: #333333;width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container .swiper-button-next{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;color: #333333;width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-wrapper{align-items: center;min-height: 350px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-pagination{bottom: 20px;}.uagb-slider-container.uagb-block-4e27f818:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-539e6df7 .swiper-content{padding-top: 87px;padding-bottom: 87px;padding-left: 87px;padding-right: 87px;background-repeat: no-repeat;background-position: 48% 34%;background-size: cover;background-attachment: scroll;background-image: linear-gradient(to right, rgba(0,0,0,0.46), rgba(0,0,0,0.46)), url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/37745.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-cfa3fb96 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cfa3fb96 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cfa3fb96 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cfa3fb96 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cfa3fb96 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cfa3fb96{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cfa3fb96 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-cfa3fb96{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.uagb-block-957cf1e0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-957cf1e0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-957cf1e0 .uagb-ifb-icon svg{fill: #333;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-957cf1e0 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-957cf1e0 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-957cf1e0 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-957cf1e0 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-957cf1e0 .uagb-ifb-title{font-size: 40px;color: #fafafa;margin-bottom: 10px;}.uagb-block-957cf1e0 .uagb-ifb-desc{font-size: 18px;color: #ffffff;margin-bottom: 20px;}.uagb-block-957cf1e0 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-957cf1e0 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-957cf1e0 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-957cf1e0 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-957cf1e0 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-957cf1e0.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-957cf1e0 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c7f84351 .swiper-content{padding-top: 83px;padding-bottom: 83px;padding-left: 83px;padding-right: 83px;background-repeat: no-repeat;background-position: 56% 76%;background-size: cover;background-attachment: scroll;background-image: linear-gradient(to right, rgba(0,0,0,0.49), rgba(0,0,0,0.49)), url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/126.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-f53ec393 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f53ec393 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f53ec393 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f53ec393 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f53ec393 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f53ec393{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f53ec393 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f53ec393{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.uagb-block-83bf24d1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-83bf24d1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-83bf24d1 .uagb-ifb-icon svg{fill: #333;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-83bf24d1 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-83bf24d1 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-83bf24d1 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-83bf24d1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-83bf24d1 .uagb-ifb-title{font-size: 40px;color: #ffffff;margin-bottom: 10px;}.uagb-block-83bf24d1 .uagb-ifb-desc{font-size: 18px;color: #ffffff;margin-bottom: 20px;}.uagb-block-83bf24d1 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-83bf24d1 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-83bf24d1 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-83bf24d1 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-83bf24d1 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-83bf24d1.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-83bf24d1 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-26ef4f97 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-26ef4f97 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-26ef4f97 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-26ef4f97 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-26ef4f97 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-26ef4f97{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-26ef4f97 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-26ef4f97{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-enbxd5ql{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-enbxd5ql > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-enbxd5ql{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/9076.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-enbxd5ql::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-8);opacity: 0.5;}.uagb-block-mfy7shn2 .uagb-ifb-title{margin-bottom: 32px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-mfy7shn2 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-mfy7shn2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-mfy7shn2 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-slider-container.uagb-block-4e27f818{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container .swiper-button-prev{width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container .swiper-button-next{width: 46px;height: 46px;line-height: 46px;}.uagb-block-539e6df7 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;background-image: linear-gradient(to right, rgba(0,0,0,0.46), rgba(0,0,0,0.46)), url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/37745.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cfa3fb96{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cfa3fb96 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-cfa3fb96{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-957cf1e0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-957cf1e0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-957cf1e0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c7f84351 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;background-image: linear-gradient(to right, rgba(0,0,0,0.49), rgba(0,0,0,0.49)), url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/126.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f53ec393{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f53ec393 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f53ec393{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-83bf24d1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-83bf24d1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-83bf24d1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-26ef4f97{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-26ef4f97 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-26ef4f97{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-enbxd5ql{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-enbxd5ql > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 342px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-enbxd5ql{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/9076.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-enbxd5ql::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-8);opacity: 0.5;}.uagb-block-mfy7shn2 .uagb-ifb-title{margin-bottom: 28px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-mfy7shn2 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-mfy7shn2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-mfy7shn2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-mfy7shn2 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-mfy7shn2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-slider-container.uagb-block-4e27f818{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-4e27f818 .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container .swiper-button-prev{width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-4e27f818.uagb-slider-container .swiper-button-next{width: 46px;height: 46px;line-height: 46px;}.uagb-block-539e6df7 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;background-image: linear-gradient(to right, rgba(0,0,0,0.46), rgba(0,0,0,0.46)), url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/37745.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cfa3fb96{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cfa3fb96 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-cfa3fb96{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-957cf1e0 .uagb-ifb-title{font-size: 38px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-957cf1e0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-957cf1e0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-957cf1e0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-957cf1e0.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-957cf1e0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c7f84351 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;background-image: linear-gradient(to right, rgba(0,0,0,0.49), rgba(0,0,0,0.49)), url(https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/04\/126.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f53ec393{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f53ec393 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f53ec393{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-83bf24d1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-83bf24d1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-83bf24d1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-83bf24d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-26ef4f97{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-26ef4f97 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-26ef4f97{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading {padding-top: 0%;padding-right: 23%;padding-bottom: 0%;padding-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555 .uagb-heading-text{margin-bottom: 24px;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 14px;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555 .uagb-heading-text{margin-bottom: 14px;}}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 4px;padding-left: 0px;}}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading {padding-bottom: 4px;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 4px;padding-left: 0px;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: #ffffff;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child:hover .uagb-icon-list__label{color: #ffffff;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-ea4137e6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-50e49639.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-50e49639.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1e3a7996.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1e3a7996.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-9c3842e2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-9c3842e2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-ea4137e6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}.wp-block-uagb-container.uagb-block-b199068a.wp-block-uagb-container{color: var(--ast-global-color-4);}.wp-block-uagb-container.uagb-block-b199068a.wp-block-uagb-container *{color: var(--ast-global-color-4);}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b199068a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b199068a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b199068a{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 64px;padding-right: 64px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 0px;border-color: inherit;background-color: var(--ast-global-color-1);;row-gap: 0px;column-gap: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__title{color: var(--ast-global-color-4);margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__desc{color: var(--ast-global-color-4);margin-bottom: 14px;}.uagb-block-f57d2104 .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-f57d2104 .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-f57d2104 .uagb-cta__content-wrap{text-align: left;}.uagb-block-f57d2104 .uagb-cta__wrap{width: 54%;text-align: left;}.uagb-block-f57d2104.wp-block-uagb-call-to-action{text-align: left;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-f57d2104 .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-f57d2104 .uagb-cta__buttons{column-gap: 15px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 54%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 46%;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-f57d2104.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}.uagb-block-f57d2104 .uagb-cta__title{font-size: 33px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b199068a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b199068a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b199068a{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-f57d2104.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 65%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 35%;}.uagb-block-f57d2104 .uagb-cta__wrap{width: 65%;text-align: left;}.uagb-block-f57d2104.wp-block-uagb-call-to-action {flex-direction: row;align-items: center;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b199068a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b199068a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b199068a{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 24px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-f57d2104.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-f57d2104 .uagb-cta__buttons{justify-content: center;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 100%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 0%;}.uagb-block-f57d2104 .uagb-cta__wrap{width: 100%;text-align: center;}.uagb-block-f57d2104.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}}.uagb-timeline__outer-wrap{position:relative}.uagb-timeline__outer-wrap .uagb-timeline__field{position:relative;display:flex;align-items:flex-start;margin-bottom:inherit;color:inherit;font-size:inherit}.uagb-timeline__outer-wrap .uagb-timeline__field:not(:last-child){margin-bottom:20px}.uagb-timeline__outer-wrap .uagb-timeline__field a{margin-bottom:inherit;text-decoration:none}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__image{position:relative;display:block;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__image img{display:inline-block;box-sizing:content-box;height:auto;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__author-link{text-transform:capitalize}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__link{display:inline-block}.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__left.hide-events .uagb-timeline__events-inner-new,.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__left.hide-events .uagb-timeline__date-new{visibility:hidden}.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__right.hide-events .uagb-timeline__events-inner-new,.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__right.hide-events .uagb-timeline__date-new{visibility:hidden}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__image a{position:relative;display:block;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__image img{display:inline-block;box-sizing:content-box}.uagb-timeline__outer-wrap .uagb-timeline__line{position:absolute;transform:translateX(-50%);-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);width:3px;background-color:#eee}.uagb-timeline__outer-wrap .uagb-timeline__line .uagb-timeline__line__inner{width:100%;background-color:#0693e3}.uagb-timeline__outer-wrap svg{display:inline-block;vertical-align:middle;font-size:16px;font-style:normal;line-height:16px}.uagb-timeline__outer-wrap .uagb-timeline__field:hover .uagb-timeline__marker{transition:all .2s ease-in-out}.uagb-timeline__outer-wrap .uagb-timeline__marker{position:relative;display:flex;z-index:1;justify-content:center;align-items:center;min-width:3em;min-height:3em;background-color:#eee;border-radius:999px;line-height:48px;transition:all .2s ease-in-out}.uagb-timeline__outer-wrap .uagb-timeline__year{position:relative;display:flex}.uagb-timeline__outer-wrap .uagb-timeline__year span{display:inline-block;padding-bottom:6px}.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__field{align-items:center}.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__left .uagb-timeline__arrow,.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__right .uagb-timeline__arrow{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__field{align-items:flex-end}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__left .uagb-timeline__arrow,.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__right .uagb-timeline__arrow{top:100%;transform:translateY(-100%)}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__date-new .uagb-timeline__date-new{padding-top:8px;padding-bottom:8px}.uagb-timeline__outer-wrap .uagb-timeline__date .uagb-timeline__inner-date-new{margin:0;white-space:nowrap}.uagb-timeline__outer-wrap .in-view i.uagb-timeline__in-view-icon{-webkit-transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-in-out;-webkit-transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-out;transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-out}.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__date-new{display:none}.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__date-new{display:none}.uagb-timeline__outer-wrap p:empty{display:none}.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__line{position:absolute;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__outer-wrap span.dashicons-admin-users.dashicons{display:inline;vertical-align:baseline;margin-right:4px}.uagb-content{word-break:break-word}.uagb-timeline__headingh1,.uagb-timeline__headingh2,.uagb-timeline__headingh3,.uagb-timeline__headingh4,.uagb-timeline__headingh5,.uagb-timeline__headingh6{margin-bottom:0}.uagb-timeline__inner-date-new p,.uagb-timeline__date-inner .uagb-timeline__inner-date-new p{margin-bottom:0}.uagb-timeline__center-block{text-align:center}.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;top:50%;right:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);border-left:13px solid #eee;transform:translateY(-50%);content:\"\";-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0;order:1}.uagb-timeline__center-block .uagb-timeline__date-hide{display:none}.uagb-timeline__center-block .uagb-timeline__field.uagb-timeline__right{flex-direction:row-reverse}.uagb-timeline__center-block .uagb-timeline__day-new,.uagb-timeline__center-block .uagb-timeline__date-new{display:block;position:relative;flex-grow:1;flex-basis:50%;max-width:100%}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{order:2}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__date-new{display:flex;justify-content:flex-start}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{position:absolute;top:0;right:-10px;width:10px;height:40px}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{order:2}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__date-new{display:flex;justify-content:flex-end}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;left:-10px;width:10px;height:40px}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__line{right:auto;left:50%}.uagb-timeline__right-block .uagb-timeline__field{flex-direction:row-reverse}.uagb-timeline__right-block .uagb-timeline__date-new{display:flex;align-items:center;margin-left:10px}.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:inherit}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%)}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;right:0;width:10px;height:40px}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__right-block .uagb-timeline__marker,.uagb-timeline__right-block .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__right-block .uagb-timeline__day-new{flex-grow:1;margin-right:14px}.uagb-timeline__right-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0}.uagb-timeline__left-block{text-align:left}.uagb-timeline__left-block .uagb-timeline__marker,.uagb-timeline__left-block .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__left-block .uagb-timeline__line{inset-inline-start:20px;inset-inline-end:auto}.uagb-timeline__left-block .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:14px}.uagb-timeline__left-block .uagb-timeline__date-new{margin-right:10px}.uagb-timeline__left-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0;order:0}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%)}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;width:10px;height:40px}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-right:13px solid #eee;border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__day-right .uagb-timeline__events-inner{text-align:right}.uagb-timeline__day-left .uagb-timeline__events-inner{text-align:left}.uagb-timeline__arrow-top .uagb-timeline__date-new .uagb-timeline__date-new{padding-top:8px;padding-bottom:8px}.uagb-timeline__events-inner-new,.uagb-timeline__arrow{transition:background .2s ease-in-out}.uagb-timeline__arrow::after{transition:border-color .2s ease-in-out}.uagb-timeline__date-new{transition:color .2s ease-in-out}.uagb-timeline__day-left .uagb-timeline__arrow::after{position:absolute;left:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after{right:0}.uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;right:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__icon{position:relative;z-index:1;vertical-align:middle;width:100px;height:100px;border-radius:50%;text-align:center;line-height:100px;-webkit-border-radius:50%}.uagb-timeline__left{text-align:left}.uagb-timeline__right{text-align:right}.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after{border-left:13px solid #eee}.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-left:13px solid #eee}.uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee}.uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee}.uagb-timeline__day-right .uagb-timeline__events-inner-new{border-radius:4px 4px 4px 4px}.uagb-timeline__day-left .uagb-timeline__events-inner-new{border-radius:4px 4px 4px 4px}.uagb-timeline__arrow{height:3em}.uagb-timeline__right-block .uagb-timeline__line{inset-inline-end:1.5em}@media screen and (max-width: 1023px){.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{right:auto;left:20px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker{-webkit-box-ordinal-group:1;-webkit-order:0;-moz-box-ordinal-group:1;-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-webkit-flex-shrink:0;-ms-flex-negative:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;-webkit-box-ordinal-group:2;-webkit-order:1;-moz-box-ordinal-group:2;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__field.uagb-timeline__right{-webkit-box-orient:unset;-webkit-box-direction:unset;-webkit-flex-direction:unset;-moz-box-orient:unset;-moz-box-direction:unset;-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;width:100%;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__field{-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-webkit-flex-direction:row-reverse;-moz-box-orient:horizontal;-moz-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker{-webkit-flex-shrink:0;-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}}@media screen and (max-width: 767px){.uagb-timeline-responsive-none .uagb-timeline__events-inner-new{padding:15px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line{right:auto;left:20px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__marker{-webkit-box-ordinal-group:1;-webkit-order:0;-moz-box-ordinal-group:1;-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-webkit-flex-shrink:0;-ms-flex-negative:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;-webkit-box-ordinal-group:2;-webkit-order:1;-moz-box-ordinal-group:2;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__day-left .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__left-block .uagb-timeline__date-new{margin-right:10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__field.uagb-timeline__right{-webkit-box-orient:unset;-webkit-box-direction:unset;-webkit-flex-direction:unset;-moz-box-orient:unset;-moz-box-direction:unset;-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__field{-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-webkit-flex-direction:row-reverse;-moz-box-orient:horizontal;-moz-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__marker{-webkit-flex-shrink:0;-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee;border-left:none}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:none;border-left:13px solid #eee}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line{right:auto;left:17.5px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line{right:17.5px;left:auto}.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__author-link,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__link_parent,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__link,.uagb-timeline__responsive-mobile.uagb-timeline__center-block a.uagb-timeline__image,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__image a,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__heading,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline-desc-content,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__date-inner,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__inner-date-new{text-align:left}.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__date-hide.uagb-timeline__date-inner{text-align:left}}@media(max-width: 976px){.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{right:auto;left:17.5px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker{-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-ms-flex-negative:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-ms-flex-positive:1;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__field.uagb-timeline__right{-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;width:100%;max-width:100%;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__field{-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker{-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__date-new{-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee;border-left:none}.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__author-link,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__link_parent,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__link,.uagb-timeline__responsive-tablet.uagb-timeline__center-block a.uagb-timeline__image,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__image a,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__heading,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline-desc-content,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__date-inner,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__inner-date-new{text-align:left}.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__date-hide.uagb-timeline__date-inner{text-align:left}}.wp-block-uagb-content-timeline .wp-block-uagb-content-timeline-child .uagb-timeline__events-inner--content .uagb-timeline__heading{margin-top:unset}.wp-block-uagb-content-timeline .wp-block-uagb-content-timeline-child .uagb-timeline__events-inner--content p.uagb-timeline-desc-content{margin-bottom:unset}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap .uagb-timeline__field{display:unset}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap .uagb-timeline__field .uagb-timeline__widget{position:relative;display:flex;align-items:flex-start;font-size:inherit;color:inherit;margin-bottom:inherit}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__left-block .uagb-timeline__date-new{display:none}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__right-block .uagb-timeline__date-new{display:none}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__widget.uagb-timeline__right{flex-direction:row-reverse}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__marker{order:1;flex-shrink:0;flex-grow:0}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{order:2;padding-left:0;padding-right:12px}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{order:2;padding-right:0;padding-left:12px}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:0;top:0;width:10px;height:40px;position:absolute}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:0;top:0;width:10px;height:40px;position:absolute}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__right-block .uagb-timeline__widget{flex-direction:row-reverse}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__widget{align-items:center}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__left .uagb-timeline__arrow,.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__right .uagb-timeline__arrow{top:50%;-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%);transform:translateY(-50%)}.wp-block-uagb-post-timeline .uagb-timeline__link_parent .uagb-timeline__link.wp-block-button__link{width:auto}.rtl .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after{right:auto;left:0}.rtl .uagb-timeline__left-block .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-new{margin-left:0;margin-right:14px}.rtl .uagb-timeline__left-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__date-new{margin-right:0;margin-left:10px}.rtl .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,.rtl .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:right}.rtl .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__right-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__date-new{margin-left:0;margin-right:10px}.rtl .uagb-timeline__right-block .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-new{margin-right:0;margin-left:14px}.rtl .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,.rtl .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:left}.rtl .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__day-right .uagb-timeline__events-inner,[dir=rtl] .uagb-timeline__day-right .uagb-timeline__events-inner{text-align:left}.rtl .uagb-timeline__day-left .uagb-timeline__events-inner,[dir=rtl] .uagb-timeline__day-left .uagb-timeline__events-inner{text-align:right}.rtl .uagb-timeline__left,[dir=rtl] .uagb-timeline__left{text-align:right}.rtl .uagb-timeline__right,[dir=rtl] .uagb-timeline__right{text-align:left}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{padding-left:12px;padding-right:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{padding-right:12px;padding-left:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:0}@media screen and (max-width: 1023px){.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{margin-left:0;margin-right:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{left:auto;right:20px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after{right:auto;left:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{right:auto;left:20px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{margin-right:0;margin-left:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-left:none;border-right:13px solid #eee}}@media screen and (max-width: 767px){.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{margin-left:0;margin-right:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{margin-right:0;margin-left:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__day-left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__day-left .uagb-timeline__events-inner-new{text-align:right}.rtl .uagb-timeline__left-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__date-new{margin-right:0;margin-left:10px}}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__heading{margin-bottom: 5px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker.uagb-timeline__in-view-icon svg{fill: #fff;color: #fff;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__heading-text{margin-bottom: 5px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__line__inner{background-color: #0693e3;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__line{background-color: #eee;width: 3px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__line{inset-inline-end: calc( 35px \/ 2 );}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__line{inset-inline-start: calc( 35px \/ 2 );}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;min-height: 35px;min-width: 35px;line-height: 35px;border: 0px solid #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__marker{margin-left: 10px;margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__marker{margin-left: 10px;margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__field:not(:last-child){margin-bottom: 15px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__date-hide.uagb-timeline__date-inner{margin-bottom: 5px;color: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__date-hide.uagb-timeline__inner-date-new{margin-bottom: 5px;color: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-new.uagb-timeline__day-left{margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-new.uagb-timeline__day-left{margin-left: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-new.uagb-timeline__day-right{margin-left: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-new.uagb-timeline__day-right{margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__date-new{font-size: 12px;color: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__date-hide.uagb-timeline__date-inner{font-size: 12px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__date-hide.uagb-timeline__date-inner{font-size: 12px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-events-new .uagb-timeline__events-inner-new{padding: 20px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__events-inner-new{background-color: #eee;border-radius: 2px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker svg{color: #333;width: 12px;fill: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker.uagb-timeline__in-view-icon{background: #0693e3;border-color: #0693e3;}@media only screen and (max-width: 976px) {.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;border: 0px solid #eee;}}@media only screen and (max-width: 767px) {.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;border: 0px solid #eee;}}\";s:2:\"js\";s:1245:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tvar swiper = new Swiper( \".uagb-block-4e27f818 .uagb-swiper\",\n\t\t{\"autoplay\":{\"delay\":3000,\"disableOnInteraction\":false,\"pauseOnMouseEnter\":true,\"stopOnLastSlide\":false},\"loop\":true,\"speed\":800,\"effect\":\"slide\",\"direction\":\"horizontal\",\"flipEffect\":{\"slideShadows\":false},\"fadeEffect\":{\"crossFade\":true},\"pagination\":{\"el\":\".uagb-block-4e27f818 .swiper-pagination\",\"clickable\":true,\"hideOnClick\":false},\"navigation\":{\"nextEl\":\".uagb-block-4e27f818 .swiper-button-next\",\"prevEl\":\".uagb-block-4e27f818 .swiper-button-prev\"},\"breakpoints\":{\"976\":{\"slidesPerView\":1,\"spaceBetween\":10},\"767\":{\"slidesPerView\":1,\"spaceBetween\":10},\"320\":{\"slidesPerView\":1,\"spaceBetween\":10}}}\t);\n});\n\nwindow.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBTimelineClasses( {\"block_id\":\"47b59b3c\",\"timelinAlignment\":\"center\",\"timelinAlignmentTablet\":\"center\",\"timelinAlignmentMobile\":\"center\"}, '.uagb-block-47b59b3c' );\n});\nwindow.addEventListener(\"resize\", function(){\n\tUAGBTimelineClasses( {\"block_id\":\"47b59b3c\",\"timelinAlignment\":\"center\",\"timelinAlignmentTablet\":\"center\",\"timelinAlignmentMobile\":\"center\"}, '.uagb-block-47b59b3c' );\n});\n });\";s:18:\"current_block_list\";a:24:{i:0;s:14:\"uagb\/container\";i:1;s:13:\"uagb\/info-box\";i:2;s:14:\"core\/paragraph\";i:3;s:11:\"uagb\/slider\";i:4;s:17:\"uagb\/slider-child\";i:6;s:26:\"essential-blocks\/post-grid\";i:7;s:10:\"core\/image\";i:8;s:31:\"essential-blocks\/call-to-action\";i:9;s:23:\"essential-blocks\/button\";i:10;s:11:\"core\/search\";i:11;s:10:\"core\/group\";i:12;s:12:\"core\/heading\";i:13;s:17:\"core\/latest-posts\";i:14;s:20:\"core\/latest-comments\";i:15;s:13:\"core\/archives\";i:16;s:15:\"core\/categories\";i:17;s:21:\"uagb\/advanced-heading\";i:18;s:14:\"uagb\/icon-list\";i:19;s:20:\"uagb\/icon-list-child\";i:21;s:19:\"uagb\/call-to-action\";i:22;s:21:\"uagb\/content-timeline\";i:23;s:27:\"uagb\/content-timeline-child\";i:24;s:31:\"ajax-search-lite\/block-asl-main\";i:25;s:14:\"core\/separator\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1782839794\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Arecibo.pr","author_link":"https:\/\/www.arecibo.pr\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/pages\/4758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/comments?post=4758"}],"version-history":[{"count":0,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/pages\/4758\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/media?parent=4758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}