{"id":4658,"date":"2025-03-20T20:16:25","date_gmt":"2025-03-20T20:16:25","guid":{"rendered":"https:\/\/www.arecibo.pr\/?p=4658"},"modified":"2026-01-21T20:45:34","modified_gmt":"2026-01-21T20:45:34","slug":"4658-2","status":"publish","type":"post","link":"https:\/\/www.arecibo.pr\/en\/4658-2\/","title":{"rendered":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-58e9102e\"><h2 class=\"uagb-heading-text\">La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo<\/h2><\/div>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"164\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-164-align\" class=\"n2-ss-align\" style=\"margin: 0 auto; max-width: 1200px;\"><div class=\"n2-padding\"><div id=\"n2-ss-164\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition\">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"blurfit\"><div class=\"n2-ss-slide-background-image\" data-blur=\"0\" data-opacity=\"100\" data-x=\"50\" data-y=\"50\" data-alt=\"\" data-title=\"\" data-blurfitmode=\"default\" style=\"margin:-14px;padding:14px\" data-globalblur=\"7\" data-bgblur=\"7\"><picture style=\"filter:blur(7px)\" class=\"skip-lazy\" data-skip-lazy=\"1\"><img decoding=\"async\" src=\"\/\/www.arecibo.pr\/wp-content\/uploads\/2026\/01\/logo-vitrina-1024x1024-1.jpeg\" alt=\"\" title=\"\" loading=\"lazy\" class=\"skip-lazy\" data-skip-lazy=\"1\"><\/picture><\/div><div class=\"n2-ss-slide-background-image\" data-blur=\"0\" data-opacity=\"100\" data-x=\"50\" data-y=\"50\" data-alt=\"\" data-title=\"\"><picture class=\"skip-lazy\" data-skip-lazy=\"1\"><img decoding=\"async\" src=\"\/\/www.arecibo.pr\/wp-content\/uploads\/2026\/01\/logo-vitrina-1024x1024-1.jpeg\" alt=\"\" title=\"\" loading=\"lazy\" class=\"skip-lazy\" data-skip-lazy=\"1\"><\/picture><\/div><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1200 600\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"341\" data-slide-public-id=\"1\" data-title=\"454407649_942362681251084_8768533740160212015_n\" class=\"n2-ss-slide n2-ow  n2-ss-slide-341\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">454407649_942362681251084_8768533740160212015_n<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-yNDFUzKRZbV3\" data-sstype=\"slide\" data-pm=\"default\"><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-4f445fb5c4a7673d30fc7487d4559f2f wp-block-paragraph\"><strong>Ubicada en el coraz\u00f3n del Paseo de Diego en Arecibo, La Vitrina PR es mucho m\u00e1s que un espacio f\u00edsico; es un punto de encuentro donde la creatividad, la comunidad y la cultura convergen para dar forma a iniciativas innovadoras. Como organizaci\u00f3n sin fines de lucro 501(c)(3), su misi\u00f3n es fomentar el desarrollo art\u00edstico y cultural en Puerto Rico, brindando un hogar para proyectos que inspiran y transforman.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-espacio-para-la-expresion-y-la-innovacion\"><strong>Un Espacio para la Expresi\u00f3n y la Innovaci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-ec862f6811fb74b4979dc53e1471cf8a wp-block-paragraph\">En <strong>La Vitrina PR<\/strong>, cada rinc\u00f3n est\u00e1 dise\u00f1ado para potenciar la creatividad y el talento local. Su propuesta se centra en:<\/p>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-f5a2679d536cf21fa06fd2732ab576c1 wp-block-paragraph\">\ud83c\udfa8 <strong>Exposiciones Art\u00edsticas<\/strong> \u2013 Un escaparate vibrante donde artistas emergentes y consolidados pueden exhibir sus obras y conectar con el p\u00fablico.<\/p>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-40babdd6f1a4c7de04f76b2eda326f15 wp-block-paragraph\">\ud83c\udfad <strong>Eventos Culturales<\/strong> \u2013 Desde presentaciones teatrales y musicales hasta cine foros y charlas inspiradoras, La Vitrina se convierte en el epicentro de la vida cultural arecibe\u00f1a.<\/p>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-f6af592e05538afe4e391fa7439271a1 wp-block-paragraph\">\ud83d\udcda <strong>Talleres y Educaci\u00f3n<\/strong> \u2013 Clases, conversatorios y encuentros que buscan educar y motivar a la comunidad en disciplinas art\u00edsticas y culturales.<\/p>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-426113bf551ef947e8e4514cc5aa566a wp-block-paragraph\">\ud83d\udca1 <strong>Colaboraciones y Apoyo a Proyectos<\/strong> \u2013 Espacio abierto a iniciativas locales que promuevan la identidad y el crecimiento cultural de la regi\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-por-que-visitar-la-vitrina-pr\"><strong>\u00bfPor qu\u00e9 visitar La Vitrina PR?<\/strong><\/h2>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-98a17138c81819d7cfab7e7494158d34 wp-block-paragraph\">\u2714\ufe0f <strong>Fomento del arte y la cultura local<\/strong> \u2013 Un espacio dise\u00f1ado para el intercambio de ideas y el crecimiento del talento puertorrique\u00f1o.<br>\u2714\ufe0f <strong>Ambiente din\u00e1mico y colaborativo<\/strong> \u2013 Ideal para conectar con artistas, emprendedores y agentes culturales.<br>\u2714\ufe0f <strong>Ubicaci\u00f3n privilegiada<\/strong> \u2013 En el Paseo de Diego de Arecibo, un \u00e1rea en constante revitalizaci\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conectate-con-la-vitrina-pr\"><strong>Con\u00e9ctate con La Vitrina PR<\/strong><\/h2>\n\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-e10a5117bf33efff2b2f313ca8fc0478 wp-block-paragraph\">\ud83d\udccd <strong>Ubicaci\u00f3n:<\/strong> Paseo de Diego, Arecibo, Puerto Rico<br>\ud83d\udcf2 <strong>Instagram:<\/strong> <a href=\"https:\/\/www.instagram.com\/lavitrinapr\/\">@lavitrinapr<\/a><br>\ud83d\udcd8 <strong>Facebook:<\/strong> <a href=\"https:\/\/www.facebook.com\/61567223456237\">La Vitrina PR<\/a><\/p>\n\n\n\t\t\t<div \n\t\t\tclass=\"wp-block-uagb-google-map uagb-google-map__wrap uagb-block-33cb0723\"\n\t\t\tstyle=\"\" >\n\t\t\t\t<embed\n\t\t\t\t\tclass=\"uagb-google-map__iframe\"\n\t\t\t\t\ttitle=\"Google Map for \"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=la%20vitrina%20arecibo&#038;z=16&#038;hl=en&#038;t=m&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\twidth=\"640\"\n\t\t\t\t\theight=\"182\"\n\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t><\/embed>\n\t\t\t<\/div>\n\t\t\t\n\n\n<p class=\"has-ast-global-color-8-color has-text-color has-link-color has-medium-font-size wp-elements-e83d0efe4dc022111f1f3e8e835bdeeb wp-block-paragraph\">\ud83c\udf1f <strong>Forma parte de este movimiento cultural y \u00fanete a la transformaci\u00f3n de Arecibo a trav\u00e9s del arte y la creatividad. \u00a1Te esperamos en La Vitrina PR!<\/strong> \ud83c\udfad\ud83c\udfa8\u2728<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo Ubicada en el coraz\u00f3n del Paseo de Diego en Arecibo, La Vitrina PR es mucho m\u00e1s que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","pmpro_default_level":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"iawp_total_views":95,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-4658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo - Arecibo.pr<\/title>\n<meta name=\"description\" content=\"Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arecibo.pr\/en\/4658-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo\" \/>\n<meta property=\"og:description\" content=\"Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arecibo.pr\/en\/4658-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Arecibo.pr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61575723174236\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T20:16:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T20:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arecibo.pr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arecibo.pr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/\"},\"author\":{\"name\":\"Arecibo.pr\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#\\\/schema\\\/person\\\/5f8934529cba0042c6a371141890605c\"},\"headline\":\"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo\",\"datePublished\":\"2025-03-20T20:16:25+00:00\",\"dateModified\":\"2026-01-21T20:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo-vitrina.jpeg\",\"articleSection\":[\"Actividades\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/\",\"name\":\"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo - Arecibo.pr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo-vitrina.jpeg\",\"datePublished\":\"2025-03-20T20:16:25+00:00\",\"dateModified\":\"2026-01-21T20:45:34+00:00\",\"description\":\"Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo-vitrina.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo-vitrina.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/4658-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.arecibo.pr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#website\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/\",\"name\":\"Arecibo.pr\",\"description\":\"La Villa del Capit&aacute;n Correa LIVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arecibo.pr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#organization\",\"name\":\"Arecibo.pr\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png\",\"width\":378,\"height\":92,\"caption\":\"Arecibo.pr\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61575723174236\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/#\\\/schema\\\/person\\\/5f8934529cba0042c6a371141890605c\",\"name\":\"Arecibo.pr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/arecibo.pr_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/arecibo.pr_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.arecibo.pr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/arecibo.pr_avatar-96x96.png\",\"caption\":\"Arecibo.pr\"},\"sameAs\":[\"http:\\\/\\\/www.arecibo.pr\"],\"url\":\"https:\\\/\\\/www.arecibo.pr\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo - Arecibo.pr","description":"Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arecibo.pr\/en\/4658-2\/","og_locale":"en_US","og_type":"article","og_title":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo","og_description":"Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a.","og_url":"https:\/\/www.arecibo.pr\/en\/4658-2\/","og_site_name":"Arecibo.pr","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61575723174236","article_published_time":"2025-03-20T20:16:25+00:00","article_modified_time":"2026-01-21T20:45:34+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg","type":"image\/jpeg"}],"author":"Arecibo.pr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arecibo.pr","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arecibo.pr\/4658-2\/#article","isPartOf":{"@id":"https:\/\/www.arecibo.pr\/4658-2\/"},"author":{"name":"Arecibo.pr","@id":"https:\/\/www.arecibo.pr\/#\/schema\/person\/5f8934529cba0042c6a371141890605c"},"headline":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo","datePublished":"2025-03-20T20:16:25+00:00","dateModified":"2026-01-21T20:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arecibo.pr\/4658-2\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/www.arecibo.pr\/#organization"},"image":{"@id":"https:\/\/www.arecibo.pr\/4658-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg","articleSection":["Actividades"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arecibo.pr\/4658-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arecibo.pr\/4658-2\/","url":"https:\/\/www.arecibo.pr\/4658-2\/","name":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo - Arecibo.pr","isPartOf":{"@id":"https:\/\/www.arecibo.pr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arecibo.pr\/4658-2\/#primaryimage"},"image":{"@id":"https:\/\/www.arecibo.pr\/4658-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg","datePublished":"2025-03-20T20:16:25+00:00","dateModified":"2026-01-21T20:45:34+00:00","description":"Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a.","breadcrumb":{"@id":"https:\/\/www.arecibo.pr\/4658-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arecibo.pr\/4658-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arecibo.pr\/4658-2\/#primaryimage","url":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg","contentUrl":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.arecibo.pr\/4658-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.arecibo.pr\/"},{"@type":"ListItem","position":2,"name":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo"}]},{"@type":"WebSite","@id":"https:\/\/www.arecibo.pr\/#website","url":"https:\/\/www.arecibo.pr\/","name":"Arecibo.pr","description":"La Villa del Capit&aacute;n Correa LIVE","publisher":{"@id":"https:\/\/www.arecibo.pr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arecibo.pr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arecibo.pr\/#organization","name":"Arecibo.pr","url":"https:\/\/www.arecibo.pr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arecibo.pr\/#\/schema\/logo\/image\/","url":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/02\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png","contentUrl":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/02\/cropped-cropped-ARECIBO_PR-_LOGO_Mesa_de_trabajo_1__2___1___2_-removebg-preview.png","width":378,"height":92,"caption":"Arecibo.pr"},"image":{"@id":"https:\/\/www.arecibo.pr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61575723174236"]},{"@type":"Person","@id":"https:\/\/www.arecibo.pr\/#\/schema\/person\/5f8934529cba0042c6a371141890605c","name":"Arecibo.pr","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/06\/arecibo.pr_avatar-96x96.png","url":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/06\/arecibo.pr_avatar-96x96.png","contentUrl":"https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/06\/arecibo.pr_avatar-96x96.png","caption":"Arecibo.pr"},"sameAs":["http:\/\/www.arecibo.pr"],"url":"https:\/\/www.arecibo.pr\/en\/author\/admin\/"}]}},"spectra_custom_meta":{"_edit_lock":["1769028353:1"],"_thumbnail_id":["4661"],"_seopress_robots_primary_cat":["none"],"_eb_attr":[""],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":["disabled"],"ast-breadcrumbs-content":[""],"ast-featured-img":["disabled"],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"_themeisle_gutenberg_block_has_review":[""],"iawp_total_views":["95"],"footnotes":[""],"wppb-ul-default-all-users-template":[""],"wppb-ul-default-single-user-template":[""],"wppb-ul-active-theme":["default"],"_edit_last":["1"],"_wpuf_form_id":[""],"_wpuf_lock_editing_post":["no"],"_eb_reusable_block_ids":["a:0:{}"],"_wpuf_res_display":["all"],"_seopress_redirections_type":["301"],"_seopress_redirections_logged_status":["both"],"_seopress_analysis_target_kw":[""],"pmpro_default_level":[""],"_yoast_indexnow_last_ping":["1769028335"],"_yoast_wpseo_primary_category":["41"],"_yoast_wpseo_focuskw":["La Vitrina PR arte en Arecibo"],"_yoast_wpseo_metadesc":["Descubre La Vitrina PR, un espacio cultural en Arecibo que promueve el arte, exposiciones, eventos y talleres. Con\u00e9ctate con la comunidad art\u00edstica local y vive la cultura puertorrique\u00f1a."],"_yoast_wpseo_linkdex":["72"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_focuskeywords":[""],"_yoast_wpseo_keywordsynonyms":[""],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"_uag_css_file_name":["uag-css-4658.css"],"_uag_js_file_name":["uag-js-4658.js"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:1;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:1;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1770939859"],"arecibo_views":["128"],"_uag_page_assets":["a:9:{s:3:\"css\";s:85095:\".wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-google-map__wrap{display:flex}.uagb-google-map__wrap .uagb-google-map__iframe{width:100%;box-shadow:none;border:none;padding:0;margin:0}.wp-block-uagb-advanced-heading.uagb-block-58e9102e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-58e9102e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-58e9102e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-58e9102e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-58e9102e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;} .uagb-block-33cb0723 .uagb-google-map__iframe{height: 182px;}@media only screen and (max-width: 976px) { .uagb-block-33cb0723 .uagb-google-map__iframe{height: 300px;}}@media only screen and (max-width: 767px) { .uagb-block-33cb0723 .uagb-google-map__iframe{height: 300px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading {padding-top: 0%;padding-right: 23%;padding-bottom: 0%;padding-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555 .uagb-heading-text{margin-bottom: 24px;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 14px;}.wp-block-uagb-advanced-heading.uagb-block-ddf47555 .uagb-heading-text{margin-bottom: 14px;}}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-bca1d697.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 4px;padding-left: 0px;}}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading {padding-bottom: 4px;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-e8a308c0.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 4px;padding-left: 0px;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: #ffffff;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child:hover .uagb-icon-list__label{color: #ffffff;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-ea4137e6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-50e49639.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-50e49639.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1e3a7996.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1e3a7996.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-9c3842e2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-9c3842e2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-ea4137e6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.wp-block-uagb-icon-list.uagb-block-ea4137e6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}.wp-block-uagb-container.uagb-block-b199068a.wp-block-uagb-container{color: var(--ast-global-color-4);}.wp-block-uagb-container.uagb-block-b199068a.wp-block-uagb-container *{color: var(--ast-global-color-4);}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b199068a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b199068a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b199068a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b199068a{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 64px;padding-right: 64px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 0px;border-color: inherit;background-color: var(--ast-global-color-1);;row-gap: 0px;column-gap: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__title{color: var(--ast-global-color-4);margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__desc{color: var(--ast-global-color-4);margin-bottom: 14px;}.uagb-block-f57d2104 .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-f57d2104 .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-f57d2104 .uagb-cta__content-wrap{text-align: left;}.uagb-block-f57d2104 .uagb-cta__wrap{width: 54%;text-align: left;}.uagb-block-f57d2104.wp-block-uagb-call-to-action{text-align: left;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-f57d2104 .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-f57d2104 .uagb-cta__buttons{column-gap: 15px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 54%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 46%;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-f57d2104.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}.uagb-block-f57d2104.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}.uagb-block-f57d2104 .uagb-cta__title{font-size: 33px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b199068a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b199068a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b199068a{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-f57d2104.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 65%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 35%;}.uagb-block-f57d2104 .uagb-cta__wrap{width: 65%;text-align: left;}.uagb-block-f57d2104.wp-block-uagb-call-to-action {flex-direction: row;align-items: center;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b199068a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b199068a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b199068a{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 24px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 0px;}.uagb-block-f57d2104.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-f57d2104.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-f57d2104 .uagb-cta__buttons{justify-content: center;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 100%;}.uagb-block-f57d2104 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 0%;}.uagb-block-f57d2104 .uagb-cta__wrap{width: 100%;text-align: center;}.uagb-block-f57d2104.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}}.uagb-timeline__outer-wrap{position:relative}.uagb-timeline__outer-wrap .uagb-timeline__field{position:relative;display:flex;align-items:flex-start;margin-bottom:inherit;color:inherit;font-size:inherit}.uagb-timeline__outer-wrap .uagb-timeline__field:not(:last-child){margin-bottom:20px}.uagb-timeline__outer-wrap .uagb-timeline__field a{margin-bottom:inherit;text-decoration:none}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__image{position:relative;display:block;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__image img{display:inline-block;box-sizing:content-box;height:auto;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__author-link{text-transform:capitalize}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__link{display:inline-block}.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__left.hide-events .uagb-timeline__events-inner-new,.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__left.hide-events .uagb-timeline__date-new{visibility:hidden}.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__right.hide-events .uagb-timeline__events-inner-new,.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__right.hide-events .uagb-timeline__date-new{visibility:hidden}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__image a{position:relative;display:block;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__image img{display:inline-block;box-sizing:content-box}.uagb-timeline__outer-wrap .uagb-timeline__line{position:absolute;transform:translateX(-50%);-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);width:3px;background-color:#eee}.uagb-timeline__outer-wrap .uagb-timeline__line .uagb-timeline__line__inner{width:100%;background-color:#0693e3}.uagb-timeline__outer-wrap svg{display:inline-block;vertical-align:middle;font-size:16px;font-style:normal;line-height:16px}.uagb-timeline__outer-wrap .uagb-timeline__field:hover .uagb-timeline__marker{transition:all .2s ease-in-out}.uagb-timeline__outer-wrap .uagb-timeline__marker{position:relative;display:flex;z-index:1;justify-content:center;align-items:center;min-width:3em;min-height:3em;background-color:#eee;border-radius:999px;line-height:48px;transition:all .2s ease-in-out}.uagb-timeline__outer-wrap .uagb-timeline__year{position:relative;display:flex}.uagb-timeline__outer-wrap .uagb-timeline__year span{display:inline-block;padding-bottom:6px}.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__field{align-items:center}.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__left .uagb-timeline__arrow,.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__right .uagb-timeline__arrow{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__field{align-items:flex-end}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__left .uagb-timeline__arrow,.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__right .uagb-timeline__arrow{top:100%;transform:translateY(-100%)}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__date-new .uagb-timeline__date-new{padding-top:8px;padding-bottom:8px}.uagb-timeline__outer-wrap .uagb-timeline__date .uagb-timeline__inner-date-new{margin:0;white-space:nowrap}.uagb-timeline__outer-wrap .in-view i.uagb-timeline__in-view-icon{-webkit-transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-in-out;-webkit-transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-out;transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-out}.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__date-new{display:none}.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__date-new{display:none}.uagb-timeline__outer-wrap p:empty{display:none}.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__line{position:absolute;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__outer-wrap span.dashicons-admin-users.dashicons{display:inline;vertical-align:baseline;margin-right:4px}.uagb-content{word-break:break-word}.uagb-timeline__headingh1,.uagb-timeline__headingh2,.uagb-timeline__headingh3,.uagb-timeline__headingh4,.uagb-timeline__headingh5,.uagb-timeline__headingh6{margin-bottom:0}.uagb-timeline__inner-date-new p,.uagb-timeline__date-inner .uagb-timeline__inner-date-new p{margin-bottom:0}.uagb-timeline__center-block{text-align:center}.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;top:50%;right:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);border-left:13px solid #eee;transform:translateY(-50%);content:\"\";-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0;order:1}.uagb-timeline__center-block .uagb-timeline__date-hide{display:none}.uagb-timeline__center-block .uagb-timeline__field.uagb-timeline__right{flex-direction:row-reverse}.uagb-timeline__center-block .uagb-timeline__day-new,.uagb-timeline__center-block .uagb-timeline__date-new{display:block;position:relative;flex-grow:1;flex-basis:50%;max-width:100%}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{order:2}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__date-new{display:flex;justify-content:flex-start}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{position:absolute;top:0;right:-10px;width:10px;height:40px}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{order:2}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__date-new{display:flex;justify-content:flex-end}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;left:-10px;width:10px;height:40px}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__line{right:auto;left:50%}.uagb-timeline__right-block .uagb-timeline__field{flex-direction:row-reverse}.uagb-timeline__right-block .uagb-timeline__date-new{display:flex;align-items:center;margin-left:10px}.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:inherit}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%)}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;right:0;width:10px;height:40px}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__right-block .uagb-timeline__marker,.uagb-timeline__right-block .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__right-block .uagb-timeline__day-new{flex-grow:1;margin-right:14px}.uagb-timeline__right-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0}.uagb-timeline__left-block{text-align:left}.uagb-timeline__left-block .uagb-timeline__marker,.uagb-timeline__left-block .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__left-block .uagb-timeline__line{inset-inline-start:20px;inset-inline-end:auto}.uagb-timeline__left-block .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:14px}.uagb-timeline__left-block .uagb-timeline__date-new{margin-right:10px}.uagb-timeline__left-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0;order:0}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%)}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;width:10px;height:40px}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-right:13px solid #eee;border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__day-right .uagb-timeline__events-inner{text-align:right}.uagb-timeline__day-left .uagb-timeline__events-inner{text-align:left}.uagb-timeline__arrow-top .uagb-timeline__date-new .uagb-timeline__date-new{padding-top:8px;padding-bottom:8px}.uagb-timeline__events-inner-new,.uagb-timeline__arrow{transition:background .2s ease-in-out}.uagb-timeline__arrow::after{transition:border-color .2s ease-in-out}.uagb-timeline__date-new{transition:color .2s ease-in-out}.uagb-timeline__day-left .uagb-timeline__arrow::after{position:absolute;left:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after{right:0}.uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;right:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__icon{position:relative;z-index:1;vertical-align:middle;width:100px;height:100px;border-radius:50%;text-align:center;line-height:100px;-webkit-border-radius:50%}.uagb-timeline__left{text-align:left}.uagb-timeline__right{text-align:right}.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after{border-left:13px solid #eee}.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-left:13px solid #eee}.uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee}.uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee}.uagb-timeline__day-right .uagb-timeline__events-inner-new{border-radius:4px 4px 4px 4px}.uagb-timeline__day-left .uagb-timeline__events-inner-new{border-radius:4px 4px 4px 4px}.uagb-timeline__arrow{height:3em}.uagb-timeline__right-block .uagb-timeline__line{inset-inline-end:1.5em}@media screen and (max-width: 1023px){.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{right:auto;left:20px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker{-webkit-box-ordinal-group:1;-webkit-order:0;-moz-box-ordinal-group:1;-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-webkit-flex-shrink:0;-ms-flex-negative:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;-webkit-box-ordinal-group:2;-webkit-order:1;-moz-box-ordinal-group:2;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__field.uagb-timeline__right{-webkit-box-orient:unset;-webkit-box-direction:unset;-webkit-flex-direction:unset;-moz-box-orient:unset;-moz-box-direction:unset;-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;width:100%;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__field{-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-webkit-flex-direction:row-reverse;-moz-box-orient:horizontal;-moz-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker{-webkit-flex-shrink:0;-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}}@media screen and (max-width: 767px){.uagb-timeline-responsive-none .uagb-timeline__events-inner-new{padding:15px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line{right:auto;left:20px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__marker{-webkit-box-ordinal-group:1;-webkit-order:0;-moz-box-ordinal-group:1;-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-webkit-flex-shrink:0;-ms-flex-negative:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;-webkit-box-ordinal-group:2;-webkit-order:1;-moz-box-ordinal-group:2;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__day-left .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__left-block .uagb-timeline__date-new{margin-right:10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__field.uagb-timeline__right{-webkit-box-orient:unset;-webkit-box-direction:unset;-webkit-flex-direction:unset;-moz-box-orient:unset;-moz-box-direction:unset;-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__field{-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-webkit-flex-direction:row-reverse;-moz-box-orient:horizontal;-moz-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__marker{-webkit-flex-shrink:0;-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee;border-left:none}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:none;border-left:13px solid #eee}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line{right:auto;left:17.5px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line{right:17.5px;left:auto}.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__author-link,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__link_parent,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__link,.uagb-timeline__responsive-mobile.uagb-timeline__center-block a.uagb-timeline__image,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__image a,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__heading,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline-desc-content,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__date-inner,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__inner-date-new{text-align:left}.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__date-hide.uagb-timeline__date-inner{text-align:left}}@media(max-width: 976px){.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{right:auto;left:17.5px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker{-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-ms-flex-negative:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-ms-flex-positive:1;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__field.uagb-timeline__right{-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;width:100%;max-width:100%;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__field{-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker{-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__date-new{-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee;border-left:none}.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__author-link,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__link_parent,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__link,.uagb-timeline__responsive-tablet.uagb-timeline__center-block a.uagb-timeline__image,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__image a,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__heading,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline-desc-content,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__date-inner,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__inner-date-new{text-align:left}.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__date-hide.uagb-timeline__date-inner{text-align:left}}.wp-block-uagb-content-timeline .wp-block-uagb-content-timeline-child .uagb-timeline__events-inner--content .uagb-timeline__heading{margin-top:unset}.wp-block-uagb-content-timeline .wp-block-uagb-content-timeline-child .uagb-timeline__events-inner--content p.uagb-timeline-desc-content{margin-bottom:unset}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap .uagb-timeline__field{display:unset}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap .uagb-timeline__field .uagb-timeline__widget{position:relative;display:flex;align-items:flex-start;font-size:inherit;color:inherit;margin-bottom:inherit}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__left-block .uagb-timeline__date-new{display:none}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__right-block .uagb-timeline__date-new{display:none}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__widget.uagb-timeline__right{flex-direction:row-reverse}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__marker{order:1;flex-shrink:0;flex-grow:0}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{order:2;padding-left:0;padding-right:12px}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{order:2;padding-right:0;padding-left:12px}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:0;top:0;width:10px;height:40px;position:absolute}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:0;top:0;width:10px;height:40px;position:absolute}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__right-block .uagb-timeline__widget{flex-direction:row-reverse}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__widget{align-items:center}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__left .uagb-timeline__arrow,.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__right .uagb-timeline__arrow{top:50%;-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%);transform:translateY(-50%)}.wp-block-uagb-post-timeline .uagb-timeline__link_parent .uagb-timeline__link.wp-block-button__link{width:auto}.rtl .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after{right:auto;left:0}.rtl .uagb-timeline__left-block .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-new{margin-left:0;margin-right:14px}.rtl .uagb-timeline__left-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__date-new{margin-right:0;margin-left:10px}.rtl .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,.rtl .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:right}.rtl .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__right-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__date-new{margin-left:0;margin-right:10px}.rtl .uagb-timeline__right-block .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-new{margin-right:0;margin-left:14px}.rtl .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,.rtl .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:left}.rtl .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__day-right .uagb-timeline__events-inner,[dir=rtl] .uagb-timeline__day-right .uagb-timeline__events-inner{text-align:left}.rtl .uagb-timeline__day-left .uagb-timeline__events-inner,[dir=rtl] .uagb-timeline__day-left .uagb-timeline__events-inner{text-align:right}.rtl .uagb-timeline__left,[dir=rtl] .uagb-timeline__left{text-align:right}.rtl .uagb-timeline__right,[dir=rtl] .uagb-timeline__right{text-align:left}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{padding-left:12px;padding-right:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{padding-right:12px;padding-left:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:0}@media screen and (max-width: 1023px){.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{margin-left:0;margin-right:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{left:auto;right:20px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after{right:auto;left:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{right:auto;left:20px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{margin-right:0;margin-left:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-left:none;border-right:13px solid #eee}}@media screen and (max-width: 767px){.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{margin-left:0;margin-right:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{margin-right:0;margin-left:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__day-left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__day-left .uagb-timeline__events-inner-new{text-align:right}.rtl .uagb-timeline__left-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__date-new{margin-right:0;margin-left:10px}}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__heading{margin-bottom: 5px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker.uagb-timeline__in-view-icon svg{fill: #fff;color: #fff;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__heading-text{margin-bottom: 5px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-left-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__line__inner{background-color: #0693e3;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__line{background-color: #eee;width: 3px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__line{inset-inline-end: calc( 35px \/ 2 );}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__line{inset-inline-start: calc( 35px \/ 2 );}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;min-height: 35px;min-width: 35px;line-height: 35px;border: 0px solid #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{height: 35px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__marker{margin-left: 10px;margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__marker{margin-left: 10px;margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__field:not(:last-child){margin-bottom: 15px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__date-hide.uagb-timeline__date-inner{margin-bottom: 5px;color: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__date-hide.uagb-timeline__inner-date-new{margin-bottom: 5px;color: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-new.uagb-timeline__day-left{margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-new.uagb-timeline__day-left{margin-left: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-new.uagb-timeline__day-right{margin-left: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-new.uagb-timeline__day-right{margin-right: 10px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__date-new{font-size: 12px;color: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__date-hide.uagb-timeline__date-inner{font-size: 12px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__date-hide.uagb-timeline__date-inner{font-size: 12px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-events-new .uagb-timeline__events-inner-new{padding: 20px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__events-inner-new{background-color: #eee;border-radius: 2px;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker svg{color: #333;width: 12px;fill: #333;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker.uagb-timeline__in-view-icon{background: #0693e3;border-color: #0693e3;}@media only screen and (max-width: 976px) {.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;border: 0px solid #eee;}}@media only screen and (max-width: 767px) {.uagb-block-47b59b3c.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-right-color: #eee;}.uagb-block-47b59b3c.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;border: 0px solid #eee;}}\";s:2:\"js\";s:510:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBTimelineClasses( {\"block_id\":\"47b59b3c\",\"timelinAlignment\":\"center\",\"timelinAlignmentTablet\":\"center\",\"timelinAlignmentMobile\":\"center\"}, '.uagb-block-47b59b3c' );\n});\nwindow.addEventListener(\"resize\", function(){\n\tUAGBTimelineClasses( {\"block_id\":\"47b59b3c\",\"timelinAlignment\":\"center\",\"timelinAlignmentTablet\":\"center\",\"timelinAlignmentMobile\":\"center\"}, '.uagb-block-47b59b3c' );\n});\n });\";s:18:\"current_block_list\";a:22:{i:0;s:14:\"core\/paragraph\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:20:\"nextend\/smartslider3\";i:3;s:14:\"core\/separator\";i:4;s:12:\"core\/heading\";i:5;s:15:\"uagb\/google-map\";i:6;s:10:\"core\/image\";i:7;s:31:\"essential-blocks\/call-to-action\";i:8;s:23:\"essential-blocks\/button\";i:9;s:11:\"core\/search\";i:10;s:10:\"core\/group\";i:11;s:17:\"core\/latest-posts\";i:12;s:20:\"core\/latest-comments\";i:13;s:13:\"core\/archives\";i:14;s:15:\"core\/categories\";i:15;s:14:\"uagb\/icon-list\";i:16;s:20:\"uagb\/icon-list-child\";i:17;s:14:\"uagb\/container\";i:18;s:19:\"uagb\/call-to-action\";i:19;s:21:\"uagb\/content-timeline\";i:20;s:27:\"uagb\/content-timeline-child\";i:21;s:31:\"ajax-search-lite\/block-asl-main\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1782839794\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg",1200,1200,false],"thumbnail":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina-150x150.jpeg",150,150,true],"medium":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina-300x300.jpeg",300,300,true],"medium_large":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina-768x768.jpeg",768,768,true],"large":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina-1024x1024.jpeg",1024,1024,true],"1536x1536":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg",1200,1200,false],"2048x2048":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg",1200,1200,false],"trp-custom-language-flag":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina-12x12.jpeg",12,12,true],"gform-image-choice-sm":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg",300,300,false],"gform-image-choice-md":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg",400,400,false],"gform-image-choice-lg":["https:\/\/www.arecibo.pr\/wp-content\/uploads\/2025\/03\/logo-vitrina.jpeg",600,600,false]},"uagb_author_info":{"display_name":"Arecibo.pr","author_link":"https:\/\/www.arecibo.pr\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"La Vitrina PR: Donde el Arte y la Cultura Cobran Vida en Arecibo Ubicada en el coraz\u00f3n del Paseo de Diego en Arecibo, La Vitrina PR es mucho m\u00e1s que [&hellip;]","_links":{"self":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/posts\/4658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/comments?post=4658"}],"version-history":[{"count":0,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/posts\/4658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/media\/4661"}],"wp:attachment":[{"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/media?parent=4658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/categories?post=4658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arecibo.pr\/en\/wp-json\/wp\/v2\/tags?post=4658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}